{"id":4,"name":"Vroni","url":"","description":"Ich bin Vroni. Ich gehe leidenschaftlich gerne essen und probiere auch gerne mal neue Restaurants, Bars, Kneipen, Caf\u00e9s etc. aus und erlebe gerne viel. Daheim hocken ist nichts f\u00fcr mich - ich will die Welt entdecken und m\u00f6glichst nichts verpassen. Au\u00dferdem interessiere ich mich f\u00fcr alle Themen rund um Freundschaft, Liebe, Beziehung, Dating und Flirten. Wenn ihr Fragen habt, nur her damit!","link":"https:\/\/www.muenchnersingles.de\/liebeskram\/author\/vroni\/","slug":"vroni","avatar_urls":{"24":"https:\/\/www.muenchnersingles.de\/liebeskram\/wp-content\/uploads\/2020\/02\/vroni-150x150.jpg","48":"https:\/\/www.muenchnersingles.de\/liebeskram\/wp-content\/uploads\/2020\/02\/vroni-150x150.jpg","96":"https:\/\/www.muenchnersingles.de\/liebeskram\/wp-content\/uploads\/2020\/02\/vroni-150x150.jpg"},"meta":{"generateblocks_onboarding":[]},"_links":{"self":[{"href":"https:\/\/www.muenchnersingles.de\/liebeskram\/wp-json\/wp\/v2\/users\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.muenchnersingles.de\/liebeskram\/wp-json\/wp\/v2\/users"}]}}